{"id":4652,"date":"2026-04-03T03:59:00","date_gmt":"2026-04-03T01:59:00","guid":{"rendered":"https:\/\/machala247.com\/?p=4652"},"modified":"2026-04-03T03:59:00","modified_gmt":"2026-04-03T01:59:00","slug":"presidente-noboa-decreta-estado-de-excepcion-en-nueve-provincias-y-cuatro-cantones-de-ecuador","status":"publish","type":"post","link":"https:\/\/machala247.com\/index.php\/2026\/04\/03\/presidente-noboa-decreta-estado-de-excepcion-en-nueve-provincias-y-cuatro-cantones-de-ecuador\/","title":{"rendered":"Presidente Noboa decreta estado de excepci\u00f3n en nueve provincias y cuatro cantones de Ecuador"},"content":{"rendered":"<p>El presidente Daniel Noboa decret\u00f3 estado de excepci\u00f3n por grave conmoci\u00f3n interna en nueve provincias y cuatro cantones de Ecuador, este jueves, 2 de abril de 2026, en la v\u00edspera del feriado de Semana Santa.<\/p>\n<p>La medida rige para Guayas, Manab\u00ed, Santa Elena, Los R\u00edos, El Oro, Pichincha, Esmeraldas, Santo Domingo de los Ts\u00e1chilas y Sucumb\u00edos, as\u00ed como en los cantones La Man\u00e1 (Cotopaxi), Las Naves y Echeand\u00eda (Bol\u00edvar) y La Troncal (Ca\u00f1ar).<\/p>\n<p>El estado de excepci\u00f3n implica suspender los derechos a la inviolabidad de domicilio e inviolabilidad de correspondencia en estas provincias y cantones. Esta vez, no incluye toque de queda como el que se mantuvo vigente en cuatro de estas provincias hasta el 30 de marzo.<\/p>\n<p>Seg\u00fan el Decreto Ejecutivo 353, esta disposici\u00f3n\u00a0tendr\u00e1 vigencia por 60 d\u00edas.<\/p>\n<h3>Operativos y allanamientos<\/h3>\n<p>El Decreto autoriza a la fuerza p\u00fablica realizar allanamientos e intervenciones de comunicaci\u00f3n cuando existan indicios de presencia de grupos armados, delincuencia organizada, armas, explosivos u otros elementos que puedan constituir delitos o amenazar la seguridad.<\/p>\n<p>El documento especifica que estas acciones deber\u00e1n cumplir con los principios de necesidad, proporcionalidad y debido proceso, dejando constancia documentada de lo actuado.<\/p>\n<p>Adem\u00e1s, se dispone el empleo coordinado de Fuerzas Armadas y Polic\u00eda Nacional en estas provincias y cantones, con el objetivo de mantener el orden p\u00fablico, proteger a la poblaci\u00f3n y prevenir actividades delictivas que afecten derechos y libertades ciudadanas.<\/p>\n<h3>Se autoriza\u00a0la requisici\u00f3n temporal de bienes<\/h3>\n<p>El decreto establece que, de manera excepcional y como \u00faltimo recurso, la fuerza p\u00fablica podr\u00e1 requisar temporalmente bienes y servicios de origen l\u00edcito que sean estrictamente necesarios para garantizar la continuidad de sus operaciones, proteger los derechos de la poblaci\u00f3n y restablecer el orden p\u00fablico en las zonas afectadas por el estado de excepci\u00f3n.<\/p>\n<p>Las requisiciones se realizar\u00e1n solo en las provincias y cantones incluidos en la declaratoria, en casos de extrema necesidad, bajo responsabilidad de las autoridades competentes, y respetando la normativa vigente. Los bienes no fungibles deber\u00e1n devolverse al finalizar la necesidad o se otorgar\u00e1 indemnizaci\u00f3n equivalente por su uso o servicio.<\/p>\n<h3>Informe de Inteligencia<\/h3>\n<p>El decreto alude a un informe reservado del Centro Nacional de Inteligencia. El documento se\u00f1ala que la violencia en el pa\u00eds no se distribuye de manera uniforme, sino que se concentra en determinadas regiones, como es el caso de estas provincias y cantones.<\/p>\n<p>El informe advierte que la situaci\u00f3n configura un escenario nacional de violencia armada estructural y persistente, que supera las capacidades del Estado bajo un r\u00e9gimen ordinario, generando un cuadro de grave conmoci\u00f3n interna que justifica la adopci\u00f3n de medidas excepcionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Daniel Noboa decret\u00f3 estado de excepci\u00f3n por grave conmoci\u00f3n interna en nueve provincias y cuatro cantones<\/p>\n","protected":false},"author":3,"featured_media":4653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecuador"],"featured_image_urls":{"full":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/04\/69cf1b4273df7.jpeg",832,468,false],"thumbnail":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/04\/69cf1b4273df7-150x150.jpeg",150,150,true],"medium":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/04\/69cf1b4273df7-300x169.jpeg",300,169,true],"medium_large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/04\/69cf1b4273df7-768x432.jpeg",640,360,true],"large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/04\/69cf1b4273df7.jpeg",640,360,false],"1536x1536":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/04\/69cf1b4273df7.jpeg",832,468,false],"2048x2048":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/04\/69cf1b4273df7.jpeg",832,468,false],"morenews-featured":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/04\/69cf1b4273df7.jpeg",832,468,false],"morenews-large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/04\/69cf1b4273df7-825x468.jpeg",825,468,true],"morenews-medium":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/04\/69cf1b4273df7-590x410.jpeg",590,410,true]},"author_info":{"display_name":"Machala 247","author_link":"https:\/\/machala247.com\/index.php\/author\/danielmorocho\/"},"category_info":"<a href=\"https:\/\/machala247.com\/index.php\/category\/ecuador\/\" rel=\"category tag\">Ecuador<\/a>","tag_info":"Ecuador","comment_count":"0","_links":{"self":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/comments?post=4652"}],"version-history":[{"count":1,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4652\/revisions"}],"predecessor-version":[{"id":4654,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4652\/revisions\/4654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/media\/4653"}],"wp:attachment":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/media?parent=4652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/categories?post=4652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/tags?post=4652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}