{"id":4551,"date":"2026-03-30T20:37:11","date_gmt":"2026-03-30T18:37:11","guid":{"rendered":"https:\/\/machala247.com\/?p=4551"},"modified":"2026-03-30T20:37:11","modified_gmt":"2026-03-30T18:37:11","slug":"tragedia-en-urdaneta-una-madre-y-sus-dos-hijos-fallecen-cuando-acudian-a-auxiliar-al-padre-de-familia","status":"publish","type":"post","link":"https:\/\/machala247.com\/index.php\/2026\/03\/30\/tragedia-en-urdaneta-una-madre-y-sus-dos-hijos-fallecen-cuando-acudian-a-auxiliar-al-padre-de-familia\/","title":{"rendered":"Tragedia en Urdaneta: Una madre y sus dos hijos fallecen cuando acud\u00edan a auxiliar al padre de familia"},"content":{"rendered":"<p data-path-to-node=\"5\"><b data-path-to-node=\"5\" data-index-in-node=\"0\">URDANETA.\u00a0<\/b>Lo que deb\u00eda ser un domingo de descanso familiar en el sector de Laguna Azul termin\u00f3 en una de las tragedias viales m\u00e1s conmovedoras de los \u00faltimos meses en la provincia de Los R\u00edos.<\/p>\n<p data-path-to-node=\"5\"><b data-path-to-node=\"5\" data-index-in-node=\"204\">Mar\u00eda de Lourdes Barahona Carriel<\/b>\u00a0y sus hijos,\u00a0<b data-path-to-node=\"5\" data-index-in-node=\"251\">Einer Yardel<\/b>\u00a0y\u00a0<b data-path-to-node=\"5\" data-index-in-node=\"266\">Natanael \u00c1lvarez Barahona<\/b>, perdieron la vida la noche del pasado domingo 29 de marzo de 2026, en un siniestro de tr\u00e1nsito en la v\u00eda Caluma-Roblesito.<\/p>\n<h3 data-path-to-node=\"6\">Una carrera contra el tiempo y la angustia<\/h3>\n<p data-path-to-node=\"7\">La fatalidad comenz\u00f3 con una llamada telef\u00f3nica. Seg\u00fan los informes preliminares,\u00a0<strong>la familia se encontraba disfrutando de una tarde recreativa cuando fueron alertados sobre un accidente sufrido por el padre de familia en el cant\u00f3n Puebloviejo.<\/strong>\u00a0La informaci\u00f3n recibida por los deudos era devastadora: les indicaron que el hombre supuestamente hab\u00eda fallecido.<\/p>\n<p data-path-to-node=\"8\">Ante la desesperaci\u00f3n, la madre y sus hijos abordaron una camioneta para trasladarse de urgencia y confirmar el estado de su ser querido. Testigos se\u00f1alan que el veh\u00edculo circulaba a alta velocidad, motivado por la emergencia familiar.<\/p>\n<h3 data-path-to-node=\"9\">El fatal impacto<\/h3>\n<p data-path-to-node=\"10\">Al llegar a las inmediaciones del recinto\u00a0<b data-path-to-node=\"10\" data-index-in-node=\"42\">Roblesito<\/b>, en el cant\u00f3n Urdaneta,\u00a0<strong>el veh\u00edculo liviano habr\u00eda ca\u00eddo en una zona de baches profundos<\/strong>, lo que provoc\u00f3 la p\u00e9rdida de control de la camioneta. Esto deriv\u00f3 en un choque frontal contra una unidad de transporte de la\u00a0<b data-path-to-node=\"10\" data-index-in-node=\"267\">Cooperativa Caluma<\/b>.<\/p>\n<p data-path-to-node=\"11\">Producto del fuerte impacto<strong>, Mar\u00eda de Lourdes y sus dos hijos fallecieron de manera casi instant\u00e1nea.<\/strong>\u00a0Se conoce que otras dos personas, presuntamente hijas de la mujer, resultaron heridas y se encuentran bajo pron\u00f3stico reservado en una casa de salud.<\/p>\n<h3 data-path-to-node=\"12\">La iron\u00eda del destino<\/h3>\n<p data-path-to-node=\"13\">La tragedia se vuelve a\u00fan m\u00e1s amarga al confirmarse que el padre de familia, a quien fueron a buscar crey\u00e9ndolo muerto,\u00a0<b data-path-to-node=\"13\" data-index-in-node=\"120\">sobrevivi\u00f3 a su accidente en motocicleta<\/b>. Actualmente, el hombre se encuentra hospitalizado recuper\u00e1ndose de sus heridas,\u00a0<strong>sin saber inicialmente que su esposa y dos de sus hijos perdieron la vida intentando llegar a su lado.<\/strong><\/p>\n<blockquote data-path-to-node=\"14\">\n<p data-path-to-node=\"14,0\">\u00abIban a ver a su padre que supuestamente hab\u00eda fallecido, pero terminaron falleciendo ellos\u00bb, comentaron allegados en las afueras del centro forense de Babahoyo.<\/p>\n<\/blockquote>\n<p data-path-to-node=\"15\">Los restos de las v\u00edctimas ser\u00e1n trasladados a su sector natal,\u00a0<b data-path-to-node=\"15\" data-index-in-node=\"64\">Pijullo<\/b>, para el velatorio. Mientras tanto, las autoridades de tr\u00e1nsito investigan las circunstancias exactas del choque y el estado de la v\u00eda, se\u00f1alada por los moradores debido al mal estado de la capa asf\u00e1ltica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>URDANETA.\u00a0Lo que deb\u00eda ser un domingo de descanso familiar en el sector de Laguna Azul termin\u00f3 en una<\/p>\n","protected":false},"author":3,"featured_media":4552,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecuador"],"featured_image_urls":{"full":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/yukyi58687.png",788,507,false],"thumbnail":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/yukyi58687-150x150.png",150,150,true],"medium":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/yukyi58687-300x193.png",300,193,true],"medium_large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/yukyi58687-768x494.png",640,412,true],"large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/yukyi58687.png",640,412,false],"1536x1536":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/yukyi58687.png",788,507,false],"2048x2048":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/yukyi58687.png",788,507,false],"morenews-featured":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/yukyi58687.png",788,507,false],"morenews-large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/yukyi58687.png",788,507,false],"morenews-medium":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/yukyi58687-590x410.png",590,410,true]},"author_info":{"display_name":"Machala 247","author_link":"https:\/\/machala247.com\/index.php\/author\/danielmorocho\/"},"category_info":"<a href=\"https:\/\/machala247.com\/index.php\/category\/ecuador\/\" rel=\"category tag\">Ecuador<\/a>","tag_info":"Ecuador","comment_count":"0","_links":{"self":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/comments?post=4551"}],"version-history":[{"count":1,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4551\/revisions"}],"predecessor-version":[{"id":4553,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4551\/revisions\/4553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/media\/4552"}],"wp:attachment":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/media?parent=4551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/categories?post=4551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/tags?post=4551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}