{"id":4544,"date":"2026-03-28T22:55:49","date_gmt":"2026-03-28T21:55:49","guid":{"rendered":"https:\/\/machala247.com\/?p=4544"},"modified":"2026-03-28T22:55:49","modified_gmt":"2026-03-28T21:55:49","slug":"siete-aprehendidos-tras-intento-de-secuestro-en-jipijapa","status":"publish","type":"post","link":"https:\/\/machala247.com\/index.php\/2026\/03\/28\/siete-aprehendidos-tras-intento-de-secuestro-en-jipijapa\/","title":{"rendered":"Siete aprehendidos tras intento de secuestro en Jipijapa."},"content":{"rendered":"<p>La r\u00e1pida intervenci\u00f3n de la Polic\u00eda Nacional evit\u00f3 que un intento de secuestro se consumara en el cant\u00f3n Jipijapa, provincia de Manab\u00ed. El operativo, ejecutado la tarde del viernes 27 de marzo, dej\u00f3 como resultado la aprehensi\u00f3n de siete personas presuntamente implicadas en el hecho.<\/p>\n<p>Eran cerca de las 15:05 cuando una alerta ciudadana encendi\u00f3 las alarmas en el sector de las calles Col\u00f3n y Bol\u00edvar, en las inmediaciones del parque central, donde se reportaba un posible secuestro en curso.<\/p>\n<p>En ese momento, agentes del Grupo de Operaciones Motorizadas (GOM), que realizaban un traslado de valores por la zona, reaccionaron de inmediato. Sin perder tiempo, los uniformados se desplegaron para ubicar a los sospechosos y contener la situaci\u00f3n.<\/p>\n<p>Seg\u00fan el informe policial, los presuntos implicados se movilizaban en un veh\u00edculo y dos motocicletas. La acci\u00f3n oportuna de los agentes permiti\u00f3 interceptarlos y neutralizarlos, frustrando as\u00ed la ejecuci\u00f3n del delito.<\/p>\n<p>Los aprehendidos fueron identificados como Milton M. y Cristhian P., ambos de 26 a\u00f1os; Javeth B.; Luis D., de 19 a\u00f1os; Carlos \u00c1., de 21; Jetly B., de 20; y Nixon R., de 25 a\u00f1os.<\/p>\n<p>La v\u00edctima, un ciudadano de 27 a\u00f1os, fue rescatada sana y salva, sin presentar afectaciones de gravedad, lo que evidenci\u00f3 la eficacia del operativo policial.<\/p>\n<p>Como parte de los indicios, las autoridades incautaron un autom\u00f3vil, dos motocicletas y varios tel\u00e9fonos celulares, los cuales fueron ingresados bajo cadena de custodia para continuar con las investigaciones.<\/p>\n<p>El caso permanece en manos de las autoridades competentes, que avanzan en las diligencias para determinar responsabilidades y esclarecer todos los detalles de este hecho que gener\u00f3 alarma entre los habitantes de Jipijapa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La r\u00e1pida intervenci\u00f3n de la Polic\u00eda Nacional evit\u00f3 que un intento de secuestro se consumara en el cant\u00f3n<\/p>\n","protected":false},"author":3,"featured_media":4545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecuador"],"featured_image_urls":{"full":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/ruo8p8np8.png",1332,720,false],"thumbnail":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/ruo8p8np8-150x150.png",150,150,true],"medium":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/ruo8p8np8-300x162.png",300,162,true],"medium_large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/ruo8p8np8-768x415.png",640,346,true],"large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/ruo8p8np8-1024x554.png",640,346,true],"1536x1536":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/ruo8p8np8.png",1332,720,false],"2048x2048":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/ruo8p8np8.png",1332,720,false],"morenews-featured":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/ruo8p8np8-1024x554.png",1024,554,true],"morenews-large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/ruo8p8np8-825x575.png",825,575,true],"morenews-medium":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/ruo8p8np8-590x410.png",590,410,true]},"author_info":{"display_name":"Machala 247","author_link":"https:\/\/machala247.com\/index.php\/author\/danielmorocho\/"},"category_info":"<a href=\"https:\/\/machala247.com\/index.php\/category\/ecuador\/\" rel=\"category tag\">Ecuador<\/a>","tag_info":"Ecuador","comment_count":"0","_links":{"self":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/comments?post=4544"}],"version-history":[{"count":1,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4544\/revisions"}],"predecessor-version":[{"id":4546,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4544\/revisions\/4546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/media\/4545"}],"wp:attachment":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/media?parent=4544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/categories?post=4544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/tags?post=4544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}