{"id":4504,"date":"2026-03-26T22:32:13","date_gmt":"2026-03-26T21:32:13","guid":{"rendered":"https:\/\/machala247.com\/?p=4504"},"modified":"2026-03-26T22:34:05","modified_gmt":"2026-03-26T21:34:05","slug":"4504","status":"publish","type":"post","link":"https:\/\/machala247.com\/index.php\/2026\/03\/26\/4504\/","title":{"rendered":"Los barrios 7 de Marzo etapa II y lotizaci\u00f3n Santa Cecilia etapa II ser\u00e1n regenerados"},"content":{"rendered":"<p>El alcalde de Machala, Ing. Dar\u00edo Macas Salvatierra, suscribir\u00e1 el contrato para la ejecuci\u00f3n del proyecto de la regeneraci\u00f3n urbana de los barrios 7 de Marzo Etapa II y Lotizaci\u00f3n Santa Cecilia Etapa II, ubicados en la parroquia La Providencia, este jueves 26 de marzo de 2026, a las 17h00, en la cancha del sector.<\/p>\n<p>El acto contar\u00e1 con la presencia de moradores de ambas barriadas, dirigentes de la parroquia La Providencia, representantes de los barrios del sector Este y autoridades cantonales.<br \/>\nEste evento p\u00fablico marcar\u00e1 el inicio de una obra largamente esperada por estas comunidades, que hist\u00f3ricamente no hab\u00edan recibido intervenci\u00f3n municipal y que hoy proyectan una transformaci\u00f3n significativa en su calidad de vida.<\/p>\n<p>El proyecto contempla la colocaci\u00f3n del mejoramiento de la base y subbase, carpeta asf\u00e1ltica de las calles, la construcci\u00f3n de bordillos, cunetas y aceras, as\u00ed como la implementaci\u00f3n de se\u00f1alizaci\u00f3n vertical y horizontal. Adem\u00e1s, incluye la instalaci\u00f3n de sistemas de agua potable mediante tuber\u00edas de diferentes di\u00e1metros, conexiones domiciliarias, v\u00e1lvulas y cajas de control sanitario; asimismo, se ejecutar\u00e1n obras de alcantarillado sanitario y pluvial que comprenden, la instalaci\u00f3n de redes de alcantarillado y la construcci\u00f3n de c\u00e1maras y sumideros, complementado con la instalaci\u00f3n de iluminaci\u00f3n p\u00fablica.<\/p>\n<p>Esta obra se ejecutar\u00e1 con una inversi\u00f3n de USD 3\u00b4538.268 que tienen como objetivo mejorar la movilidad peatonal y vehicular, garantizar servicios b\u00e1sicos eficientemente y elevar la calidad de vida de los cientos de familias que habitan en estos sectores.<\/p>\n<p>El alcalde expres\u00f3 su satisfacci\u00f3n de poder atender a los moradores de estos sectores muy populares del cant\u00f3n mediante obras que reivindican su derecho a vivir en condiciones dignas.<\/p>\n<p>Con esta intervenci\u00f3n, el Municipio de Machala inicia la regeneraci\u00f3n de otro importante sector del cant\u00f3n, que se suma a los proyectos ejecutados en distintas zonas de la ciudad, donde actualmente sus habitantes ya disfrutan de mejores condiciones urbanas y acceso a servicios b\u00e1sicos de calidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El alcalde de Machala, Ing. Dar\u00edo Macas Salvatierra, suscribir\u00e1 el contrato para la ejecuci\u00f3n del proyecto de la<\/p>\n","protected":false},"author":3,"featured_media":4505,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,46,13],"tags":[],"class_list":["post-4504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-oro","category-local","category-portada"],"featured_image_urls":{"full":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-9.36.43-AM.jpeg",1600,900,false],"thumbnail":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-9.36.43-AM-150x150.jpeg",150,150,true],"medium":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-9.36.43-AM-300x169.jpeg",300,169,true],"medium_large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-9.36.43-AM-768x432.jpeg",640,360,true],"large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-9.36.43-AM-1024x576.jpeg",640,360,true],"1536x1536":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-9.36.43-AM-1536x864.jpeg",1536,864,true],"2048x2048":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-9.36.43-AM.jpeg",1600,900,false],"morenews-featured":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-9.36.43-AM-1024x576.jpeg",1024,576,true],"morenews-large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-9.36.43-AM-825x575.jpeg",825,575,true],"morenews-medium":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-9.36.43-AM-590x410.jpeg",590,410,true]},"author_info":{"display_name":"Machala 247","author_link":"https:\/\/machala247.com\/index.php\/author\/danielmorocho\/"},"category_info":"<a href=\"https:\/\/machala247.com\/index.php\/category\/el-oro\/\" rel=\"category tag\">El Oro<\/a> <a href=\"https:\/\/machala247.com\/index.php\/category\/local\/\" rel=\"category tag\">Local<\/a> <a href=\"https:\/\/machala247.com\/index.php\/category\/portada\/\" rel=\"category tag\">Portada<\/a>","tag_info":"Portada","comment_count":"0","_links":{"self":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/comments?post=4504"}],"version-history":[{"count":2,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4504\/revisions"}],"predecessor-version":[{"id":4507,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4504\/revisions\/4507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/media\/4505"}],"wp:attachment":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/media?parent=4504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/categories?post=4504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/tags?post=4504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}