{"id":4456,"date":"2026-03-25T02:41:38","date_gmt":"2026-03-25T01:41:38","guid":{"rendered":"https:\/\/machala247.com\/?p=4456"},"modified":"2026-03-25T02:41:38","modified_gmt":"2026-03-25T01:41:38","slug":"gabriel-achilier-vuelve-a-orense-sporting-club","status":"publish","type":"post","link":"https:\/\/machala247.com\/index.php\/2026\/03\/25\/gabriel-achilier-vuelve-a-orense-sporting-club\/","title":{"rendered":"Gabriel Achilier vuelve a Orense Sporting Club"},"content":{"rendered":"<p>Orense Sporting Club anunci\u00f3 de manera sorpresiva el retorno a Gabriel Achilier, referente y capit\u00e1n del club en los \u00faltimos a\u00f1os. Este anuncio se realiz\u00f3 la tarde de este martes 24 de marzo, en el marco de la rueda de prensa de presentaci\u00f3n de Hern\u00e1n Torres como nuevo director t\u00e9cnico del equipo bananero.<\/p>\n<p>El momento fue totalmente inesperado. Mientras la rueda de prensa se desarrollaba con normalidad, el Ing. Darwin Palacios, vicepresidente y fundador del club, anunci\u00f3 el regreso del experimentado defensor, expresando: \u201cBienvenido a tu casa, Gabriel\u201d. Acto seguido, el jugador orense hizo su ingreso a la mesa principal, causando sorpresa entre los medios de comunicaci\u00f3n presentes.<\/p>\n<p>Posteriormente, Achilier brind\u00f3 sus primeras declaraciones, en las que manifest\u00f3: \u201cAgradecido con los directivos. Estoy muy contento, ya que es un regalo maravilloso que Dios me ha dado poder reintegrarme al club. Sin duda, m\u00e1s agradecido con Dios no puedo estar\u201d.<\/p>\n<p>Gabriel Achilier ha formado parte del equipo de la provincia durante cinco temporadas, en las que fue capit\u00e1n en todas las campa\u00f1as.<br \/>\nDurante ese periodo disput\u00f3 139 partidos y anot\u00f3 10 goles. A inicios del presente a\u00f1o se hab\u00eda anunciado su despedida del equipo \u201cbananero\u201d; sin embargo, tras varias conversaciones con la directiva, se concret\u00f3 su regreso hasta el final de la temporada 2026.<\/p>\n<p>El jugador se integrar\u00e1 a los entrenamientos durante esta semana, bajo la direcci\u00f3n del profesor Hern\u00e1n Torres, con el objetivo de ponerse a punto de cara a la reanudaci\u00f3n del torneo, tras la fecha FIFA, cuando el equipo visitar\u00e1 a Independiente del Valle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orense Sporting Club anunci\u00f3 de manera sorpresiva el retorno a Gabriel Achilier, referente y capit\u00e1n del club en<\/p>\n","protected":false},"author":3,"featured_media":4457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-4456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"featured_image_urls":{"full":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/1-2.png",1332,720,false],"thumbnail":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/1-2-150x150.png",150,150,true],"medium":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/1-2-300x162.png",300,162,true],"medium_large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/1-2-768x415.png",640,346,true],"large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/1-2-1024x554.png",640,346,true],"1536x1536":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/1-2.png",1332,720,false],"2048x2048":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/1-2.png",1332,720,false],"morenews-featured":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/1-2-1024x554.png",1024,554,true],"morenews-large":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/1-2-825x575.png",825,575,true],"morenews-medium":["https:\/\/machala247.com\/wp-content\/uploads\/2026\/03\/1-2-590x410.png",590,410,true]},"author_info":{"display_name":"Machala 247","author_link":"https:\/\/machala247.com\/index.php\/author\/danielmorocho\/"},"category_info":"<a href=\"https:\/\/machala247.com\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","tag_info":"Deportes","comment_count":"0","_links":{"self":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/comments?post=4456"}],"version-history":[{"count":1,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4456\/revisions"}],"predecessor-version":[{"id":4458,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/posts\/4456\/revisions\/4458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/media\/4457"}],"wp:attachment":[{"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/media?parent=4456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/categories?post=4456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/machala247.com\/index.php\/wp-json\/wp\/v2\/tags?post=4456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}